{"id":2822,"date":"2015-01-01T16:09:01","date_gmt":"2015-01-01T15:09:01","guid":{"rendered":"https:\/\/www.patagonia-biking.com\/patagonia-integrale\/"},"modified":"2017-04-01T20:27:09","modified_gmt":"2017-04-01T18:27:09","slug":"patagonia-integrale","status":"publish","type":"post","link":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/","title":{"rendered":"Final y comienzo de a\u00f1o en Patagonia"},"content":{"rendered":"<p>A fines de diciembre realizamos un viaje de cicloturismo en la Patagonia desde Puerto Montt a Bariloche y casi en continuaci\u00f3n iniciamos nuestra traves\u00eda en bicicleta m\u00e1s larga, la Patagonia longitudinal: Bariloche-Ushuaia.<\/p>\n<p>En estos momentos estamos pasando por Calafate, camino a Puerto Natales y en una breve pausa de viaje, aprovechamos para compartir algunas fotos del viaje anterior.<\/p>\n<p>A los amigos de Patagonia-Biking, con inter\u00e9s en seguir viajando con nosotros, los invitamos a ver nuestro programa anual y les informamos, que ya hemos formado un grupo para realizar el viaje de Costa Rica y la India, en los que todav\u00eda nos queda alg\u00fan lugar.<\/p>\n<p>Tambi\u00e9n estamos formando los grupos para el viaje del Noroeste de Argentina (Humahuaca y Acay), en marzo. Cuba, Italia y Nepal-Tibet. Si queres viajar con nosotros, te pedimos que nos contactes con anticipaci\u00f3n.<\/p>\n<p>Tenemos traves\u00edas en bicicleta para todos los gustos, desde f\u00e1ciles a exigentes &#8211; mayormente por la altura que se pedalea. Para los que deseen algo \u00abespecial\u00bb: no dejen de consultarnos por nuestros \u00abviajes a medida\u00bb, para grupos privados.<\/p>\n<p>Si desea acompa\u00f1arnos en nuestros viajes virtualmente, como siempre, los invitamos a compartir nuestras fotos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fines de diciembre realizamos un viaje de cicloturismo en la Patagonia desde Puerto Montt a Bariloche y casi en continuaci\u00f3n iniciamos nuestra traves\u00eda en bicicleta m\u00e1s larga, la Patagonia longitudinal: Bariloche-Ushuaia. En estos momentos estamos pasando por Calafate, camino a Puerto Natales y en una breve pausa de viaje, aprovechamos para compartir algunas fotos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"types":[46],"class_list":["post-2822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","types-travels-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking<\/title>\n<meta name=\"description\" content=\"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking\" \/>\n<meta property=\"og:description\" content=\"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Biking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatagoniaBiking\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-01T15:09:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-01T18:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Guerini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Guerini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/\"},\"author\":{\"name\":\"Marco Guerini\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\"},\"headline\":\"Final y comienzo de a\u00f1o en Patagonia\",\"datePublished\":\"2015-01-01T15:09:01+00:00\",\"dateModified\":\"2017-04-01T18:27:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/\"},\"wordCount\":209,\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/01.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/\",\"name\":\"Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/01.jpg\",\"datePublished\":\"2015-01-01T15:09:01+00:00\",\"dateModified\":\"2017-04-01T18:27:09+00:00\",\"description\":\"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/01.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-integrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Final y comienzo de a\u00f1o en Patagonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"name\":\"Patagonia Biking\",\"description\":\"Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"alternateName\":\"Patagonia-Biking.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patagonia-biking.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\",\"name\":\"Patagonia Biking\",\"alternateName\":\"patagonia-biking.com\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"width\":696,\"height\":696,\"caption\":\"Patagonia Biking\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatagoniaBiking\",\"https:\\\/\\\/www.instagram.com\\\/patagoniabiking\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\",\"name\":\"Marco Guerini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"caption\":\"Marco Guerini\"},\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/author\\\/marco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking","description":"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/","og_locale":"es_ES","og_type":"article","og_title":"Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking","og_description":"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","og_url":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/","og_site_name":"Patagonia Biking","article_publisher":"https:\/\/www.facebook.com\/PatagoniaBiking","article_published_time":"2015-01-01T15:09:01+00:00","article_modified_time":"2017-04-01T18:27:09+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg","type":"image\/jpeg"}],"author":"Marco Guerini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marco Guerini","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#article","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/"},"author":{"name":"Marco Guerini","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1"},"headline":"Final y comienzo de a\u00f1o en Patagonia","datePublished":"2015-01-01T15:09:01+00:00","dateModified":"2017-04-01T18:27:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/"},"wordCount":209,"publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/","url":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/","name":"Final y comienzo de a\u00f1o en Patagonia- Patagonia Biking","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#primaryimage"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg","datePublished":"2015-01-01T15:09:01+00:00","dateModified":"2017-04-01T18:27:09+00:00","description":"Final y comienzo de a\u00f1o en Patagonia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","breadcrumb":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#primaryimage","url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg","contentUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/01\/01.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-integrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patagonia-biking.com\/es\/"},{"@type":"ListItem","position":2,"name":"Final y comienzo de a\u00f1o en Patagonia"}]},{"@type":"WebSite","@id":"https:\/\/www.patagonia-biking.com\/#website","url":"https:\/\/www.patagonia-biking.com\/","name":"Patagonia Biking","description":"Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"alternateName":"Patagonia-Biking.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patagonia-biking.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.patagonia-biking.com\/#organization","name":"Patagonia Biking","alternateName":"patagonia-biking.com","url":"https:\/\/www.patagonia-biking.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","width":696,"height":696,"caption":"Patagonia Biking"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatagoniaBiking","https:\/\/www.instagram.com\/patagoniabiking\/"]},{"@type":"Person","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1","name":"Marco Guerini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","caption":"Marco Guerini"},"url":"https:\/\/www.patagonia-biking.com\/es\/author\/marco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts\/2822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/comments?post=2822"}],"version-history":[{"count":2,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts\/2822\/revisions"}],"predecessor-version":[{"id":2824,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts\/2822\/revisions\/2824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/media\/1255"}],"wp:attachment":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/media?parent=2822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/categories?post=2822"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/types?post=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}