{"id":8521,"date":"2018-02-18T06:39:44","date_gmt":"2018-02-18T05:39:44","guid":{"rendered":"https:\/\/www.patagonia-biking.com\/patagonia-calafate-ushuaia-5\/"},"modified":"2018-02-18T06:39:44","modified_gmt":"2018-02-18T05:39:44","slug":"patagonia-calafate-ushuaia-5","status":"publish","type":"post","link":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/","title":{"rendered":"Patagonia Calafate Ushuaia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":8409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"types":[46],"class_list":["post-8521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","types-travels-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patagonia Calafate Ushuaia- Patagonia Biking<\/title>\n<meta name=\"description\" content=\"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patagonia Calafate Ushuaia- Patagonia Biking\" \/>\n<meta property=\"og:description\" content=\"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Biking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatagoniaBiking\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-18T05:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Guerini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Guerini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/\"},\"author\":{\"name\":\"Marco Guerini\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\"},\"headline\":\"Patagonia Calafate Ushuaia\",\"datePublished\":\"2018-02-18T05:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1.jpg.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/\",\"name\":\"Patagonia Calafate Ushuaia- Patagonia Biking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1.jpg.jpg\",\"datePublished\":\"2018-02-18T05:39:44+00:00\",\"description\":\"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1.jpg.jpg\",\"width\":800,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/patagonia-calafate-ushuaia-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patagonia Calafate Ushuaia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"name\":\"Patagonia Biking\",\"description\":\"Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"alternateName\":\"Patagonia-Biking.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patagonia-biking.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\",\"name\":\"Patagonia Biking\",\"alternateName\":\"patagonia-biking.com\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"width\":696,\"height\":696,\"caption\":\"Patagonia Biking\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatagoniaBiking\",\"https:\\\/\\\/www.instagram.com\\\/patagoniabiking\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\",\"name\":\"Marco Guerini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"caption\":\"Marco Guerini\"},\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/es\\\/author\\\/marco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patagonia Calafate Ushuaia- Patagonia Biking","description":"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/","og_locale":"es_ES","og_type":"article","og_title":"Patagonia Calafate Ushuaia- Patagonia Biking","og_description":"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","og_url":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/","og_site_name":"Patagonia Biking","article_publisher":"https:\/\/www.facebook.com\/PatagoniaBiking","article_published_time":"2018-02-18T05:39:44+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg","type":"image\/jpeg"}],"author":"Marco Guerini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marco Guerini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#article","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/"},"author":{"name":"Marco Guerini","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1"},"headline":"Patagonia Calafate Ushuaia","datePublished":"2018-02-18T05:39:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/"},"wordCount":3,"publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/","url":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/","name":"Patagonia Calafate Ushuaia- Patagonia Biking","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#primaryimage"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg","datePublished":"2018-02-18T05:39:44+00:00","description":"Patagonia Calafate Ushuaia bike travelPatagonia Biking Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","breadcrumb":{"@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#primaryimage","url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg","contentUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2018\/02\/1.jpg.jpg","width":800,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.patagonia-biking.com\/es\/patagonia-calafate-ushuaia-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patagonia-biking.com\/es\/"},{"@type":"ListItem","position":2,"name":"Patagonia Calafate Ushuaia"}]},{"@type":"WebSite","@id":"https:\/\/www.patagonia-biking.com\/#website","url":"https:\/\/www.patagonia-biking.com\/","name":"Patagonia Biking","description":"Organizamos viajes de cicloturismo en Sudam\u00e9rica, Centroam\u00e9rica, Europa y Asia, descubriendo lugares remotos con naturaleza intacta y paisajes \u00fanicos.","publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"alternateName":"Patagonia-Biking.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patagonia-biking.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.patagonia-biking.com\/#organization","name":"Patagonia Biking","alternateName":"patagonia-biking.com","url":"https:\/\/www.patagonia-biking.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","width":696,"height":696,"caption":"Patagonia Biking"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatagoniaBiking","https:\/\/www.instagram.com\/patagoniabiking\/"]},{"@type":"Person","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1","name":"Marco Guerini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","caption":"Marco Guerini"},"url":"https:\/\/www.patagonia-biking.com\/es\/author\/marco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts\/8521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/comments?post=8521"}],"version-history":[{"count":0,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/posts\/8521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/media\/8409"}],"wp:attachment":[{"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/media?parent=8521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/categories?post=8521"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/es\/wp-json\/wp\/v2\/types?post=8521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}