{"id":901,"date":"2015-09-01T21:10:06","date_gmt":"2015-09-01T19:10:06","guid":{"rendered":"https:\/\/www.patagonia-biking.com\/it\/?p=901"},"modified":"2017-03-08T20:31:40","modified_gmt":"2017-03-08T19:31:40","slug":"traversata-delle-alpi-da-trieste-a-nizza","status":"publish","type":"post","link":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/","title":{"rendered":"Traversata delle Alpi da Trieste a Nizza&#8230;"},"content":{"rendered":"<p>1700 km &#8211; 25 passi- 33.000 m di dislivello.<br \/>\nCifre che sicuramente fanno pensare ad allenamenti sostenuti e a un percorso solo per professionisti.<br \/>\nNon \u00e8 cos\u00ec! Un allenamento medio, una buona dose di determinazione e la coesione del gruppo ha permesso a tutti i partecipanti di questa prima edizione delle Alpi di pedalare interamente il percorso.<br \/>\nI ritmi tranquilli e varie soste durante la giornata per integrare energia, hanno permesso inoltre di godere maggiormente della pedalata e giungere alla meta finale unanimi nel pensare che le Alpi sono bellissime.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1700 km &#8211; 25 passi- 33.000 m di dislivello. Cifre che sicuramente fanno pensare ad allenamenti sostenuti e a un percorso solo per professionisti. Non \u00e8 cos\u00ec! Un allenamento medio, una buona dose di determinazione e la coesione del gruppo ha permesso a tutti i partecipanti di questa prima edizione delle Alpi di pedalare interamente [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"types":[27],"class_list":["post-901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","types-travels-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking<\/title>\n<meta name=\"description\" content=\"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking\" \/>\n<meta property=\"og:description\" content=\"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Patagonia Biking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PatagoniaBiking\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-01T19:10:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-08T19:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Guerini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Guerini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/\"},\"author\":{\"name\":\"Marco Guerini\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\"},\"headline\":\"Traversata delle Alpi da Trieste a Nizza&#8230;\",\"datePublished\":\"2015-09-01T19:10:06+00:00\",\"dateModified\":\"2017-03-08T19:31:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/01.jpg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/\",\"name\":\"Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/01.jpg\",\"datePublished\":\"2015-09-01T19:10:06+00:00\",\"dateModified\":\"2017-03-08T19:31:40+00:00\",\"description\":\"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/01.jpg\",\"width\":598,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/traversata-delle-alpi-da-trieste-a-nizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traversata delle Alpi da Trieste a Nizza&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#website\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"name\":\"Patagonia Biking\",\"description\":\"Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\"},\"alternateName\":\"Patagonia-Biking.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patagonia-biking.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#organization\",\"name\":\"Patagonia Biking\",\"alternateName\":\"patagonia-biking.com\",\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.patagonia-biking.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Marca-x696.jpg?fit=696%2C696&ssl=1\",\"width\":696,\"height\":696,\"caption\":\"Patagonia Biking\"},\"image\":{\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PatagoniaBiking\",\"https:\\\/\\\/www.instagram.com\\\/patagoniabiking\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.patagonia-biking.com\\\/#\\\/schema\\\/person\\\/5d67a20c2e2ef06652b94ce55b6370d1\",\"name\":\"Marco Guerini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g\",\"caption\":\"Marco Guerini\"},\"url\":\"https:\\\/\\\/www.patagonia-biking.com\\\/it\\\/author\\\/marco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking","description":"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/","og_locale":"it_IT","og_type":"article","og_title":"Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking","og_description":"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.","og_url":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/","og_site_name":"Patagonia Biking","article_publisher":"https:\/\/www.facebook.com\/PatagoniaBiking","article_published_time":"2015-09-01T19:10:06+00:00","article_modified_time":"2017-03-08T19:31:40+00:00","og_image":[{"width":598,"height":400,"url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg","type":"image\/jpeg"}],"author":"Marco Guerini","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marco Guerini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#article","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/"},"author":{"name":"Marco Guerini","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1"},"headline":"Traversata delle Alpi da Trieste a Nizza&#8230;","datePublished":"2015-09-01T19:10:06+00:00","dateModified":"2017-03-08T19:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/"},"wordCount":93,"publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/","url":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/","name":"Traversata delle Alpi da Trieste a Nizza...- Patagonia Biking","isPartOf":{"@id":"https:\/\/www.patagonia-biking.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#primaryimage"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg","datePublished":"2015-09-01T19:10:06+00:00","dateModified":"2017-03-08T19:31:40+00:00","description":"Traversata delle Alpi da Trieste a Nizza... bike travelPatagonia Biking Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.","breadcrumb":{"@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#primaryimage","url":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg","contentUrl":"https:\/\/www.patagonia-biking.com\/wp-content\/uploads\/2015\/09\/01.jpg","width":598,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.patagonia-biking.com\/it\/traversata-delle-alpi-da-trieste-a-nizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patagonia-biking.com\/it\/"},{"@type":"ListItem","position":2,"name":"Traversata delle Alpi da Trieste a Nizza&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.patagonia-biking.com\/#website","url":"https:\/\/www.patagonia-biking.com\/","name":"Patagonia Biking","description":"Organizziamo viaggi di cicloturismo in Sud America, Centro America, Europa e Asia, alla scoperta di luoghi remoti con natura intatta e paesaggi unici.","publisher":{"@id":"https:\/\/www.patagonia-biking.com\/#organization"},"alternateName":"Patagonia-Biking.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patagonia-biking.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.patagonia-biking.com\/#organization","name":"Patagonia Biking","alternateName":"patagonia-biking.com","url":"https:\/\/www.patagonia-biking.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.patagonia-biking.com\/wp-content\/uploads\/2025\/05\/Marca-x696.jpg?fit=696%2C696&ssl=1","width":696,"height":696,"caption":"Patagonia Biking"},"image":{"@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PatagoniaBiking","https:\/\/www.instagram.com\/patagoniabiking\/"]},{"@type":"Person","@id":"https:\/\/www.patagonia-biking.com\/#\/schema\/person\/5d67a20c2e2ef06652b94ce55b6370d1","name":"Marco Guerini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b27e81392f9243fe6a228c5fa05206200b1add6b4ffa9dc28806fbd8edf5d638?s=96&d=mm&r=g","caption":"Marco Guerini"},"url":"https:\/\/www.patagonia-biking.com\/it\/author\/marco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/posts\/901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":1,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/posts\/901\/revisions"}],"predecessor-version":[{"id":902,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/posts\/901\/revisions\/902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/media\/903"}],"wp:attachment":[{"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/media?parent=901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/categories?post=901"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/www.patagonia-biking.com\/it\/wp-json\/wp\/v2\/types?post=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}